{"id":15515,"date":"2021-03-11T12:09:35","date_gmt":"2021-03-11T11:09:35","guid":{"rendered":"https:\/\/atapspa.it\/?p=15515"},"modified":"2021-03-11T12:09:35","modified_gmt":"2021-03-11T11:09:35","slug":"linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione","status":"publish","type":"post","link":"https:\/\/www.atapspa.it\/en\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/","title":{"rendered":"(Italiano) Linea 300 Biella \u2013 Cossato &#8211; Valle Mosso &#8211; Trivero  Coincidenze a Valle Mosso autostazione"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.atapspa.it\/it\/wp-json\/wp\/v2\/posts\/15515\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italiano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Italiano.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-15515","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atapspa.it\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]Linea 300 Biella \u2013 Cossato - Valle Mosso - Trivero Coincidenze a Valle Mosso autostazione [:] - Atap S.p.a.\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Italiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atapspa.it\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Atap S.p.a.\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-11T11:09:35+00:00\" \/>\n<meta name=\"author\" content=\"Andrea Dal Ponte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Dal Ponte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\\\/\"},\"author\":{\"name\":\"Andrea Dal Ponte\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/22baa47e1d19a8d554984a2ac74ca73a\"},\"headline\":\"(Italiano) Linea 300 Biella \u2013 Cossato &#8211; Valle Mosso &#8211; Trivero Coincidenze a Valle Mosso autostazione\",\"datePublished\":\"2021-03-11T11:09:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\\\/\"},\"wordCount\":106,\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\\\/\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\\\/\",\"name\":\"[:it]Linea 300 Biella \u2013 Cossato - Valle Mosso - Trivero Coincidenze a Valle Mosso autostazione [:] - Atap S.p.a.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\"},\"datePublished\":\"2021-03-11T11:09:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/22baa47e1d19a8d554984a2ac74ca73a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.atapspa.it\\\/news\\\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Linea 300 Biella \u2013 Cossato &#8211; Valle Mosso &#8211; Trivero Coincidenze a Valle Mosso autostazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\",\"name\":\"Atap S.p.a.\",\"description\":\"Atap, in viaggio con voi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/22baa47e1d19a8d554984a2ac74ca73a\",\"name\":\"Andrea Dal Ponte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g\",\"caption\":\"Andrea Dal Ponte\"},\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/author\\\/dalponte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]Linea 300 Biella \u2013 Cossato - Valle Mosso - Trivero Coincidenze a Valle Mosso autostazione [:] - Atap S.p.a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atapspa.it\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/","og_locale":"en_US","og_type":"article","og_title":"[:it]Linea 300 Biella \u2013 Cossato - Valle Mosso - Trivero Coincidenze a Valle Mosso autostazione [:] - Atap S.p.a.","og_description":"Sorry, this entry is only available in Italiano.","og_url":"https:\/\/www.atapspa.it\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/","og_site_name":"Atap S.p.a.","article_published_time":"2021-03-11T11:09:35+00:00","author":"Andrea Dal Ponte","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Andrea Dal Ponte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.atapspa.it\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/#article","isPartOf":{"@id":"https:\/\/www.atapspa.it\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/"},"author":{"name":"Andrea Dal Ponte","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/22baa47e1d19a8d554984a2ac74ca73a"},"headline":"(Italiano) Linea 300 Biella \u2013 Cossato &#8211; Valle Mosso &#8211; Trivero Coincidenze a Valle Mosso autostazione","datePublished":"2021-03-11T11:09:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.atapspa.it\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/"},"wordCount":106,"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.atapspa.it\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/","url":"https:\/\/www.atapspa.it\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/","name":"[:it]Linea 300 Biella \u2013 Cossato - Valle Mosso - Trivero Coincidenze a Valle Mosso autostazione [:] - Atap S.p.a.","isPartOf":{"@id":"https:\/\/www.atapspa.it\/en\/#website"},"datePublished":"2021-03-11T11:09:35+00:00","author":{"@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/22baa47e1d19a8d554984a2ac74ca73a"},"breadcrumb":{"@id":"https:\/\/www.atapspa.it\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atapspa.it\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.atapspa.it\/news\/linea-300-biella-cossato-valle-mosso-trivero-coincidenze-a-valle-mosso-autostazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atapspa.it\/en\/"},{"@type":"ListItem","position":2,"name":"Linea 300 Biella \u2013 Cossato &#8211; Valle Mosso &#8211; Trivero Coincidenze a Valle Mosso autostazione"}]},{"@type":"WebSite","@id":"https:\/\/www.atapspa.it\/en\/#website","url":"https:\/\/www.atapspa.it\/en\/","name":"Atap S.p.a.","description":"Atap, in viaggio con voi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atapspa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/22baa47e1d19a8d554984a2ac74ca73a","name":"Andrea Dal Ponte","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g","caption":"Andrea Dal Ponte"},"url":"https:\/\/www.atapspa.it\/en\/author\/dalponte\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 07:59:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/15515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/comments?post=15515"}],"version-history":[{"count":1,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/15515\/revisions"}],"predecessor-version":[{"id":15517,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/15515\/revisions\/15517"}],"wp:attachment":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/media?parent=15515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/categories?post=15515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/tags?post=15515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}