{"id":15959,"date":"2021-05-25T08:13:07","date_gmt":"2021-05-25T07:13:07","guid":{"rendered":"https:\/\/atapspa.it\/?p=15959"},"modified":"2021-05-28T08:13:20","modified_gmt":"2021-05-28T07:13:20","slug":"sciopero-nazionale-del-01-giugno-2021","status":"publish","type":"post","link":"https:\/\/www.atapspa.it\/en\/news\/sciopero-nazionale-del-01-giugno-2021\/","title":{"rendered":"(Italiano) Sciopero Nazionale del 01 Giugno 2021 di 24 ore con salvaguardia delle fasce protette"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.atapspa.it\/it\/wp-json\/wp\/v2\/posts\/15959\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italiano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Italiano.<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-15959","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atapspa.it\/news\/sciopero-nazionale-del-01-giugno-2021\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]Sciopero Nazionale del 01 Giugno 2021 di 24 ore con salvaguardia delle fasce protette[:] - Atap S.p.a.\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Italiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atapspa.it\/news\/sciopero-nazionale-del-01-giugno-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Atap S.p.a.\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-25T07:13:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-28T07:13:20+00:00\" \/>\n<meta name=\"author\" content=\"Fabrizio Paluan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabrizio Paluan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/news\\\/sciopero-nazionale-del-01-giugno-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/news\\\/sciopero-nazionale-del-01-giugno-2021\\\/\"},\"author\":{\"name\":\"Fabrizio Paluan\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/#\\\/schema\\\/person\\\/608f5ee5f06d7d1b879cba642ae2ba2a\"},\"headline\":\"(Italiano) Sciopero Nazionale del 01 Giugno 2021 di 24 ore con salvaguardia delle fasce protette\",\"datePublished\":\"2021-05-25T07:13:07+00:00\",\"dateModified\":\"2021-05-28T07:13:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/news\\\/sciopero-nazionale-del-01-giugno-2021\\\/\"},\"wordCount\":157,\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/news\\\/sciopero-nazionale-del-01-giugno-2021\\\/\",\"url\":\"https:\\\/\\\/atapspa.it\\\/news\\\/sciopero-nazionale-del-01-giugno-2021\\\/\",\"name\":\"[:it]Sciopero Nazionale del 01 Giugno 2021 di 24 ore con salvaguardia delle fasce protette[:] - Atap S.p.a.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/#website\"},\"datePublished\":\"2021-05-25T07:13:07+00:00\",\"dateModified\":\"2021-05-28T07:13:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/#\\\/schema\\\/person\\\/608f5ee5f06d7d1b879cba642ae2ba2a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/news\\\/sciopero-nazionale-del-01-giugno-2021\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/atapspa.it\\\/news\\\/sciopero-nazionale-del-01-giugno-2021\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/news\\\/sciopero-nazionale-del-01-giugno-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.atapspa.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sciopero Nazionale del 01 Giugno 2021 di 24 ore con salvaguardia delle fasce protette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/#website\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/\",\"name\":\"Atap S.p.a.\",\"description\":\"Atap, in viaggio con voi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atapspa.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/#\\\/schema\\\/person\\\/608f5ee5f06d7d1b879cba642ae2ba2a\",\"name\":\"Fabrizio Paluan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4d38815f2e60ee809e63079219f0e1838f9cfd1386901b355b83ffe6efb788f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4d38815f2e60ee809e63079219f0e1838f9cfd1386901b355b83ffe6efb788f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4d38815f2e60ee809e63079219f0e1838f9cfd1386901b355b83ffe6efb788f?s=96&d=mm&r=g\",\"caption\":\"Fabrizio Paluan\"},\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/author\\\/paluan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]Sciopero Nazionale del 01 Giugno 2021 di 24 ore con salvaguardia delle fasce protette[:] - Atap S.p.a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atapspa.it\/news\/sciopero-nazionale-del-01-giugno-2021\/","og_locale":"en_US","og_type":"article","og_title":"[:it]Sciopero Nazionale del 01 Giugno 2021 di 24 ore con salvaguardia delle fasce protette[:] - Atap S.p.a.","og_description":"Sorry, this entry is only available in Italiano.","og_url":"https:\/\/atapspa.it\/news\/sciopero-nazionale-del-01-giugno-2021\/","og_site_name":"Atap S.p.a.","article_published_time":"2021-05-25T07:13:07+00:00","article_modified_time":"2021-05-28T07:13:20+00:00","author":"Fabrizio Paluan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Fabrizio Paluan","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/atapspa.it\/news\/sciopero-nazionale-del-01-giugno-2021\/#article","isPartOf":{"@id":"https:\/\/atapspa.it\/news\/sciopero-nazionale-del-01-giugno-2021\/"},"author":{"name":"Fabrizio Paluan","@id":"https:\/\/www.atapspa.it\/#\/schema\/person\/608f5ee5f06d7d1b879cba642ae2ba2a"},"headline":"(Italiano) Sciopero Nazionale del 01 Giugno 2021 di 24 ore con salvaguardia delle fasce protette","datePublished":"2021-05-25T07:13:07+00:00","dateModified":"2021-05-28T07:13:20+00:00","mainEntityOfPage":{"@id":"https:\/\/atapspa.it\/news\/sciopero-nazionale-del-01-giugno-2021\/"},"wordCount":157,"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/atapspa.it\/news\/sciopero-nazionale-del-01-giugno-2021\/","url":"https:\/\/atapspa.it\/news\/sciopero-nazionale-del-01-giugno-2021\/","name":"[:it]Sciopero Nazionale del 01 Giugno 2021 di 24 ore con salvaguardia delle fasce protette[:] - Atap S.p.a.","isPartOf":{"@id":"https:\/\/www.atapspa.it\/#website"},"datePublished":"2021-05-25T07:13:07+00:00","dateModified":"2021-05-28T07:13:20+00:00","author":{"@id":"https:\/\/www.atapspa.it\/#\/schema\/person\/608f5ee5f06d7d1b879cba642ae2ba2a"},"breadcrumb":{"@id":"https:\/\/atapspa.it\/news\/sciopero-nazionale-del-01-giugno-2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atapspa.it\/news\/sciopero-nazionale-del-01-giugno-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/atapspa.it\/news\/sciopero-nazionale-del-01-giugno-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atapspa.it\/"},{"@type":"ListItem","position":2,"name":"Sciopero Nazionale del 01 Giugno 2021 di 24 ore con salvaguardia delle fasce protette"}]},{"@type":"WebSite","@id":"https:\/\/www.atapspa.it\/#website","url":"https:\/\/www.atapspa.it\/","name":"Atap S.p.a.","description":"Atap, in viaggio con voi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atapspa.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.atapspa.it\/#\/schema\/person\/608f5ee5f06d7d1b879cba642ae2ba2a","name":"Fabrizio Paluan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c4d38815f2e60ee809e63079219f0e1838f9cfd1386901b355b83ffe6efb788f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c4d38815f2e60ee809e63079219f0e1838f9cfd1386901b355b83ffe6efb788f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c4d38815f2e60ee809e63079219f0e1838f9cfd1386901b355b83ffe6efb788f?s=96&d=mm&r=g","caption":"Fabrizio Paluan"},"url":"https:\/\/www.atapspa.it\/en\/author\/paluan\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 18:22:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/15959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/comments?post=15959"}],"version-history":[{"count":1,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/15959\/revisions"}],"predecessor-version":[{"id":15961,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/15959\/revisions\/15961"}],"wp:attachment":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/media?parent=15959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/categories?post=15959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/tags?post=15959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}