{"id":19277,"date":"2022-10-14T09:50:34","date_gmt":"2022-10-14T08:50:34","guid":{"rendered":"https:\/\/atapspa.it\/?p=19277"},"modified":"2025-06-04T07:54:06","modified_gmt":"2025-06-04T06:54:06","slug":"%e2%9a%bd-pro-vercelli-piacenza-a-vercelli","status":"publish","type":"post","link":"https:\/\/www.atapspa.it\/en\/non-in-vista\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\/","title":{"rendered":"(Italiano) \u26bd \u00abPro Vercelli \u2013 Piacenza\u00bb a Vercelli"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.atapspa.it\/it\/wp-json\/wp\/v2\/posts\/19277\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italiano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Italiano.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-19277","post","type-post","status-publish","format-standard","hentry","category-non-in-vista"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atapspa.it\/en\/non-in-vista\/\u26bd-pro-vercelli-piacenza-a-vercelli\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]\u26bd \u00abPro Vercelli \u2013 Piacenza\u00bb a Vercelli[:] - Atap S.p.a.\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Italiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atapspa.it\/en\/non-in-vista\/\u26bd-pro-vercelli-piacenza-a-vercelli\/\" \/>\n<meta property=\"og:site_name\" content=\"Atap S.p.a.\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-14T08:50:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T06:54:06+00:00\" \/>\n<meta name=\"author\" content=\"Andrea Ciocca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Ciocca\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/non-in-vista\\\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/non-in-vista\\\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\\\/\"},\"author\":{\"name\":\"Andrea Ciocca\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/ab591becbdaf2ffb718df544e71b899a\"},\"headline\":\"(Italiano) \u26bd \u00abPro Vercelli \u2013 Piacenza\u00bb a Vercelli\",\"datePublished\":\"2022-10-14T08:50:34+00:00\",\"dateModified\":\"2025-06-04T06:54:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/non-in-vista\\\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\\\/\"},\"wordCount\":93,\"articleSection\":[\"Non in vista\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/non-in-vista\\\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\\\/\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/non-in-vista\\\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\\\/\",\"name\":\"[:it]\u26bd \u00abPro Vercelli \u2013 Piacenza\u00bb a Vercelli[:] - Atap S.p.a.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\"},\"datePublished\":\"2022-10-14T08:50:34+00:00\",\"dateModified\":\"2025-06-04T06:54:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/ab591becbdaf2ffb718df544e71b899a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/non-in-vista\\\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.atapspa.it\\\/en\\\/non-in-vista\\\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/non-in-vista\\\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(Italiano) \u26bd \u00abPro Vercelli \u2013 Piacenza\u00bb a Vercelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\",\"name\":\"Atap S.p.a.\",\"description\":\"Atap, in viaggio con voi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/ab591becbdaf2ffb718df544e71b899a\",\"name\":\"Andrea Ciocca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/edaf23a1d3618af7ab74eea5b4e039152d1bdf160034ab68b3030afde8cbd3b7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/edaf23a1d3618af7ab74eea5b4e039152d1bdf160034ab68b3030afde8cbd3b7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/edaf23a1d3618af7ab74eea5b4e039152d1bdf160034ab68b3030afde8cbd3b7?s=96&d=mm&r=g\",\"caption\":\"Andrea Ciocca\"},\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/author\\\/a-ciocca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]\u26bd \u00abPro Vercelli \u2013 Piacenza\u00bb a Vercelli[:] - Atap S.p.a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atapspa.it\/en\/non-in-vista\/\u26bd-pro-vercelli-piacenza-a-vercelli\/","og_locale":"en_US","og_type":"article","og_title":"[:it]\u26bd \u00abPro Vercelli \u2013 Piacenza\u00bb a Vercelli[:] - Atap S.p.a.","og_description":"Sorry, this entry is only available in Italiano.","og_url":"https:\/\/www.atapspa.it\/en\/non-in-vista\/\u26bd-pro-vercelli-piacenza-a-vercelli\/","og_site_name":"Atap S.p.a.","article_published_time":"2022-10-14T08:50:34+00:00","article_modified_time":"2025-06-04T06:54:06+00:00","author":"Andrea Ciocca","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Andrea Ciocca"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.atapspa.it\/en\/non-in-vista\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\/#article","isPartOf":{"@id":"https:\/\/www.atapspa.it\/en\/non-in-vista\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\/"},"author":{"name":"Andrea Ciocca","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/ab591becbdaf2ffb718df544e71b899a"},"headline":"(Italiano) \u26bd \u00abPro Vercelli \u2013 Piacenza\u00bb a Vercelli","datePublished":"2022-10-14T08:50:34+00:00","dateModified":"2025-06-04T06:54:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.atapspa.it\/en\/non-in-vista\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\/"},"wordCount":93,"articleSection":["Non in vista"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.atapspa.it\/en\/non-in-vista\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\/","url":"https:\/\/www.atapspa.it\/en\/non-in-vista\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\/","name":"[:it]\u26bd \u00abPro Vercelli \u2013 Piacenza\u00bb a Vercelli[:] - Atap S.p.a.","isPartOf":{"@id":"https:\/\/www.atapspa.it\/en\/#website"},"datePublished":"2022-10-14T08:50:34+00:00","dateModified":"2025-06-04T06:54:06+00:00","author":{"@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/ab591becbdaf2ffb718df544e71b899a"},"breadcrumb":{"@id":"https:\/\/www.atapspa.it\/en\/non-in-vista\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atapspa.it\/en\/non-in-vista\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.atapspa.it\/en\/non-in-vista\/%e2%9a%bd-pro-vercelli-piacenza-a-vercelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atapspa.it\/en\/"},{"@type":"ListItem","position":2,"name":"(Italiano) \u26bd \u00abPro Vercelli \u2013 Piacenza\u00bb a Vercelli"}]},{"@type":"WebSite","@id":"https:\/\/www.atapspa.it\/en\/#website","url":"https:\/\/www.atapspa.it\/en\/","name":"Atap S.p.a.","description":"Atap, in viaggio con voi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atapspa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/ab591becbdaf2ffb718df544e71b899a","name":"Andrea Ciocca","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/edaf23a1d3618af7ab74eea5b4e039152d1bdf160034ab68b3030afde8cbd3b7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/edaf23a1d3618af7ab74eea5b4e039152d1bdf160034ab68b3030afde8cbd3b7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edaf23a1d3618af7ab74eea5b4e039152d1bdf160034ab68b3030afde8cbd3b7?s=96&d=mm&r=g","caption":"Andrea Ciocca"},"url":"https:\/\/www.atapspa.it\/en\/author\/a-ciocca\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 05:07:04","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/19277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/comments?post=19277"}],"version-history":[{"count":1,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/19277\/revisions"}],"predecessor-version":[{"id":19279,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/19277\/revisions\/19279"}],"wp:attachment":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/media?parent=19277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/categories?post=19277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/tags?post=19277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}