{"id":21376,"date":"2023-10-27T11:41:48","date_gmt":"2023-10-27T10:41:48","guid":{"rendered":"https:\/\/atapspa.it\/?p=21376"},"modified":"2026-01-28T18:25:21","modified_gmt":"2026-01-28T17:25:21","slug":"aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023","status":"publish","type":"post","link":"https:\/\/www.atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/","title":{"rendered":"(Italiano) Aggiornamento\/Integrazione \u2013 Mancata erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 27\/10\/2023"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.atapspa.it\/it\/wp-json\/wp\/v2\/posts\/21376\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italiano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Italiano.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-21376","post","type-post","status-publish","format-standard","hentry","category-non-in-vista"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]Aggiornamento\/Integrazione \u2013 Mancata erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 27\/10\/2023[:] - Atap S.p.a.\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Italiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Atap S.p.a.\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-27T10:41:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T17:25:21+00:00\" \/>\n<meta name=\"author\" content=\"Andrea Dal Ponte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Dal Ponte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/non-in-vista\\\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/non-in-vista\\\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\\\/\"},\"author\":{\"name\":\"Andrea Dal Ponte\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/22baa47e1d19a8d554984a2ac74ca73a\"},\"headline\":\"(Italiano) Aggiornamento\\\/Integrazione \u2013 Mancata erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 27\\\/10\\\/2023\",\"datePublished\":\"2023-10-27T10:41:48+00:00\",\"dateModified\":\"2026-01-28T17:25:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/non-in-vista\\\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\\\/\"},\"wordCount\":171,\"image\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/non-in-vista\\\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/atapspa.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/27.10.23_integrazione.png\",\"articleSection\":[\"Non in vista\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/non-in-vista\\\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\\\/\",\"url\":\"https:\\\/\\\/atapspa.it\\\/en\\\/non-in-vista\\\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\\\/\",\"name\":\"[:it]Aggiornamento\\\/Integrazione \u2013 Mancata erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 27\\\/10\\\/2023[:] - Atap S.p.a.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/non-in-vista\\\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/non-in-vista\\\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/atapspa.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/27.10.23_integrazione.png\",\"datePublished\":\"2023-10-27T10:41:48+00:00\",\"dateModified\":\"2026-01-28T17:25:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/22baa47e1d19a8d554984a2ac74ca73a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/non-in-vista\\\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/atapspa.it\\\/en\\\/non-in-vista\\\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/non-in-vista\\\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/atapspa.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/27.10.23_integrazione.png\",\"contentUrl\":\"https:\\\/\\\/atapspa.it\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/27.10.23_integrazione.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/non-in-vista\\\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(Italiano) Aggiornamento\\\/Integrazione \u2013 Mancata erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 27\\\/10\\\/2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\",\"name\":\"Atap S.p.a.\",\"description\":\"Atap, in viaggio con voi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/22baa47e1d19a8d554984a2ac74ca73a\",\"name\":\"Andrea Dal Ponte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g\",\"caption\":\"Andrea Dal Ponte\"},\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/author\\\/dalponte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]Aggiornamento\/Integrazione \u2013 Mancata erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 27\/10\/2023[:] - Atap S.p.a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/","og_locale":"en_US","og_type":"article","og_title":"[:it]Aggiornamento\/Integrazione \u2013 Mancata erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 27\/10\/2023[:] - Atap S.p.a.","og_description":"Sorry, this entry is only available in Italiano.","og_url":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/","og_site_name":"Atap S.p.a.","article_published_time":"2023-10-27T10:41:48+00:00","article_modified_time":"2026-01-28T17:25:21+00:00","author":"Andrea Dal Ponte","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Andrea Dal Ponte","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/#article","isPartOf":{"@id":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/"},"author":{"name":"Andrea Dal Ponte","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/22baa47e1d19a8d554984a2ac74ca73a"},"headline":"(Italiano) Aggiornamento\/Integrazione \u2013 Mancata erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 27\/10\/2023","datePublished":"2023-10-27T10:41:48+00:00","dateModified":"2026-01-28T17:25:21+00:00","mainEntityOfPage":{"@id":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/"},"wordCount":171,"image":{"@id":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/atapspa.it\/wp-content\/uploads\/2023\/10\/27.10.23_integrazione.png","articleSection":["Non in vista"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/","url":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/","name":"[:it]Aggiornamento\/Integrazione \u2013 Mancata erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 27\/10\/2023[:] - Atap S.p.a.","isPartOf":{"@id":"https:\/\/www.atapspa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/#primaryimage"},"image":{"@id":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/atapspa.it\/wp-content\/uploads\/2023\/10\/27.10.23_integrazione.png","datePublished":"2023-10-27T10:41:48+00:00","dateModified":"2026-01-28T17:25:21+00:00","author":{"@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/22baa47e1d19a8d554984a2ac74ca73a"},"breadcrumb":{"@id":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/#primaryimage","url":"https:\/\/atapspa.it\/wp-content\/uploads\/2023\/10\/27.10.23_integrazione.png","contentUrl":"https:\/\/atapspa.it\/wp-content\/uploads\/2023\/10\/27.10.23_integrazione.png"},{"@type":"BreadcrumbList","@id":"https:\/\/atapspa.it\/en\/non-in-vista\/aggiornamento-integrazione-mancata-erogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-27-10-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atapspa.it\/en\/"},{"@type":"ListItem","position":2,"name":"(Italiano) Aggiornamento\/Integrazione \u2013 Mancata erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 27\/10\/2023"}]},{"@type":"WebSite","@id":"https:\/\/www.atapspa.it\/en\/#website","url":"https:\/\/www.atapspa.it\/en\/","name":"Atap S.p.a.","description":"Atap, in viaggio con voi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atapspa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/22baa47e1d19a8d554984a2ac74ca73a","name":"Andrea Dal Ponte","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g","caption":"Andrea Dal Ponte"},"url":"https:\/\/www.atapspa.it\/en\/author\/dalponte\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 07:17:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/21376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/comments?post=21376"}],"version-history":[{"count":3,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/21376\/revisions"}],"predecessor-version":[{"id":21400,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/21376\/revisions\/21400"}],"wp:attachment":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/media?parent=21376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/categories?post=21376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/tags?post=21376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}