{"id":21765,"date":"2023-12-19T15:32:36","date_gmt":"2023-12-19T14:32:36","guid":{"rendered":"https:\/\/atapspa.it\/?p=21765"},"modified":"2023-12-19T15:35:59","modified_gmt":"2023-12-19T14:35:59","slug":"%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2","status":"publish","type":"post","link":"https:\/\/www.atapspa.it\/en\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/","title":{"rendered":"(Italiano) \ud83c\udf84Messa della notte di Natale al Santuario di Oropa"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.atapspa.it\/it\/wp-json\/wp\/v2\/posts\/21765\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italiano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Italiano.<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-21765","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atapspa.it\/news\/\ud83c\udf84messa-della-notte-di-natale-al-santuario-di-oropa-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]\ud83c\udf84Messa della notte di Natale al Santuario di Oropa[:] - Atap S.p.a.\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Italiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atapspa.it\/news\/\ud83c\udf84messa-della-notte-di-natale-al-santuario-di-oropa-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Atap S.p.a.\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-19T14:32:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-19T14:35:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/atapspa.it\/wp-content\/uploads\/2023\/12\/messa-Natale-23.png\" \/>\n<meta name=\"author\" content=\"Sabrina Lorenzon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sabrina Lorenzon\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\\\/\"},\"author\":{\"name\":\"Sabrina Lorenzon\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/db9a93dba3500869b86f1eeb1a7b8d14\"},\"headline\":\"(Italiano) \ud83c\udf84Messa della notte di Natale al Santuario di Oropa\",\"datePublished\":\"2023-12-19T14:32:36+00:00\",\"dateModified\":\"2023-12-19T14:35:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\\\/\"},\"wordCount\":75,\"image\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/atapspa.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/messa-Natale-23.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\\\/\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\\\/\",\"name\":\"[:it]\ud83c\udf84Messa della notte di Natale al Santuario di Oropa[:] - Atap S.p.a.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/atapspa.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/messa-Natale-23.png\",\"datePublished\":\"2023-12-19T14:32:36+00:00\",\"dateModified\":\"2023-12-19T14:35:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/db9a93dba3500869b86f1eeb1a7b8d14\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.atapspa.it\\\/news\\\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/atapspa.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/messa-Natale-23.png\",\"contentUrl\":\"https:\\\/\\\/atapspa.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/messa-Natale-23.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/news\\\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ud83c\udf84Messa della notte di Natale al Santuario di Oropa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\",\"name\":\"Atap S.p.a.\",\"description\":\"Atap, in viaggio con voi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/db9a93dba3500869b86f1eeb1a7b8d14\",\"name\":\"Sabrina Lorenzon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d00766c1945d4518ecdbc8124af8ffe4396c9936ff79507bf7d3584c037d5ea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d00766c1945d4518ecdbc8124af8ffe4396c9936ff79507bf7d3584c037d5ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d00766c1945d4518ecdbc8124af8ffe4396c9936ff79507bf7d3584c037d5ea?s=96&d=mm&r=g\",\"caption\":\"Sabrina Lorenzon\"},\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/author\\\/lorenzon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]\ud83c\udf84Messa della notte di Natale al Santuario di Oropa[:] - Atap S.p.a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atapspa.it\/news\/\ud83c\udf84messa-della-notte-di-natale-al-santuario-di-oropa-2\/","og_locale":"en_US","og_type":"article","og_title":"[:it]\ud83c\udf84Messa della notte di Natale al Santuario di Oropa[:] - Atap S.p.a.","og_description":"Sorry, this entry is only available in Italiano.","og_url":"https:\/\/www.atapspa.it\/news\/\ud83c\udf84messa-della-notte-di-natale-al-santuario-di-oropa-2\/","og_site_name":"Atap S.p.a.","article_published_time":"2023-12-19T14:32:36+00:00","article_modified_time":"2023-12-19T14:35:59+00:00","og_image":[{"url":"https:\/\/atapspa.it\/wp-content\/uploads\/2023\/12\/messa-Natale-23.png","type":"","width":"","height":""}],"author":"Sabrina Lorenzon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Sabrina Lorenzon"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.atapspa.it\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/#article","isPartOf":{"@id":"https:\/\/www.atapspa.it\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/"},"author":{"name":"Sabrina Lorenzon","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/db9a93dba3500869b86f1eeb1a7b8d14"},"headline":"(Italiano) \ud83c\udf84Messa della notte di Natale al Santuario di Oropa","datePublished":"2023-12-19T14:32:36+00:00","dateModified":"2023-12-19T14:35:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.atapspa.it\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/"},"wordCount":75,"image":{"@id":"https:\/\/www.atapspa.it\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/#primaryimage"},"thumbnailUrl":"https:\/\/atapspa.it\/wp-content\/uploads\/2023\/12\/messa-Natale-23.png","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.atapspa.it\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/","url":"https:\/\/www.atapspa.it\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/","name":"[:it]\ud83c\udf84Messa della notte di Natale al Santuario di Oropa[:] - Atap S.p.a.","isPartOf":{"@id":"https:\/\/www.atapspa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.atapspa.it\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/#primaryimage"},"image":{"@id":"https:\/\/www.atapspa.it\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/#primaryimage"},"thumbnailUrl":"https:\/\/atapspa.it\/wp-content\/uploads\/2023\/12\/messa-Natale-23.png","datePublished":"2023-12-19T14:32:36+00:00","dateModified":"2023-12-19T14:35:59+00:00","author":{"@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/db9a93dba3500869b86f1eeb1a7b8d14"},"breadcrumb":{"@id":"https:\/\/www.atapspa.it\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atapspa.it\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.atapspa.it\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/#primaryimage","url":"https:\/\/atapspa.it\/wp-content\/uploads\/2023\/12\/messa-Natale-23.png","contentUrl":"https:\/\/atapspa.it\/wp-content\/uploads\/2023\/12\/messa-Natale-23.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.atapspa.it\/news\/%f0%9f%8e%84messa-della-notte-di-natale-al-santuario-di-oropa-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atapspa.it\/en\/"},{"@type":"ListItem","position":2,"name":"\ud83c\udf84Messa della notte di Natale al Santuario di Oropa"}]},{"@type":"WebSite","@id":"https:\/\/www.atapspa.it\/en\/#website","url":"https:\/\/www.atapspa.it\/en\/","name":"Atap S.p.a.","description":"Atap, in viaggio con voi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atapspa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/db9a93dba3500869b86f1eeb1a7b8d14","name":"Sabrina Lorenzon","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0d00766c1945d4518ecdbc8124af8ffe4396c9936ff79507bf7d3584c037d5ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0d00766c1945d4518ecdbc8124af8ffe4396c9936ff79507bf7d3584c037d5ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d00766c1945d4518ecdbc8124af8ffe4396c9936ff79507bf7d3584c037d5ea?s=96&d=mm&r=g","caption":"Sabrina Lorenzon"},"url":"https:\/\/www.atapspa.it\/en\/author\/lorenzon\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 07:17:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/21765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/comments?post=21765"}],"version-history":[{"count":1,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/21765\/revisions"}],"predecessor-version":[{"id":21767,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/21765\/revisions\/21767"}],"wp:attachment":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/media?parent=21765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/categories?post=21765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/tags?post=21765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}