{"id":22207,"date":"2024-03-14T12:26:21","date_gmt":"2024-03-14T11:26:21","guid":{"rendered":"https:\/\/atapspa.it\/?p=22207"},"modified":"2026-01-28T18:16:35","modified_gmt":"2026-01-28T17:16:35","slug":"criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024","status":"publish","type":"post","link":"https:\/\/www.atapspa.it\/en\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/","title":{"rendered":"(Italiano) Criticit\u00e0 relative all\u2019erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 15\/03\/2024"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.atapspa.it\/it\/wp-json\/wp\/v2\/posts\/22207\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italiano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Italiano.<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-22207","post","type-post","status-publish","format-standard","hentry","category-non-in-vista"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]Criticit\u00e0 relative all\u2019erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 15\/03\/2024[:] - Atap S.p.a.\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Italiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Atap S.p.a.\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-14T11:26:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T17:16:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/atapspa.it\/wp-content\/uploads\/2024\/03\/15.03.2024.png\" \/>\n<meta name=\"author\" content=\"Sabrina Lorenzon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sabrina Lorenzon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/non-in-vista\\\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/non-in-vista\\\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\\\/\"},\"author\":{\"name\":\"Sabrina Lorenzon\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/db9a93dba3500869b86f1eeb1a7b8d14\"},\"headline\":\"(Italiano) Criticit\u00e0 relative all\u2019erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 15\\\/03\\\/2024\",\"datePublished\":\"2024-03-14T11:26:21+00:00\",\"dateModified\":\"2026-01-28T17:16:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/non-in-vista\\\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\\\/\"},\"wordCount\":163,\"image\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/non-in-vista\\\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/atapspa.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/15.03.2024.png\",\"articleSection\":[\"Non in vista\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/non-in-vista\\\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\\\/\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/non-in-vista\\\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\\\/\",\"name\":\"[:it]Criticit\u00e0 relative all\u2019erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 15\\\/03\\\/2024[:] - Atap S.p.a.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/non-in-vista\\\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/non-in-vista\\\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/atapspa.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/15.03.2024.png\",\"datePublished\":\"2024-03-14T11:26:21+00:00\",\"dateModified\":\"2026-01-28T17:16:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/db9a93dba3500869b86f1eeb1a7b8d14\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/non-in-vista\\\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.atapspa.it\\\/non-in-vista\\\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/non-in-vista\\\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/atapspa.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/15.03.2024.png\",\"contentUrl\":\"https:\\\/\\\/atapspa.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/15.03.2024.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/non-in-vista\\\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Criticit\u00e0 relative all\u2019erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 15\\\/03\\\/2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\",\"name\":\"Atap S.p.a.\",\"description\":\"Atap, in viaggio con voi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/db9a93dba3500869b86f1eeb1a7b8d14\",\"name\":\"Sabrina Lorenzon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d00766c1945d4518ecdbc8124af8ffe4396c9936ff79507bf7d3584c037d5ea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d00766c1945d4518ecdbc8124af8ffe4396c9936ff79507bf7d3584c037d5ea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d00766c1945d4518ecdbc8124af8ffe4396c9936ff79507bf7d3584c037d5ea?s=96&d=mm&r=g\",\"caption\":\"Sabrina Lorenzon\"},\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/author\\\/lorenzon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]Criticit\u00e0 relative all\u2019erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 15\/03\/2024[:] - Atap S.p.a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/","og_locale":"en_US","og_type":"article","og_title":"[:it]Criticit\u00e0 relative all\u2019erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 15\/03\/2024[:] - Atap S.p.a.","og_description":"Sorry, this entry is only available in Italiano.","og_url":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/","og_site_name":"Atap S.p.a.","article_published_time":"2024-03-14T11:26:21+00:00","article_modified_time":"2026-01-28T17:16:35+00:00","og_image":[{"url":"https:\/\/atapspa.it\/wp-content\/uploads\/2024\/03\/15.03.2024.png","type":"","width":"","height":""}],"author":"Sabrina Lorenzon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Sabrina Lorenzon","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/#article","isPartOf":{"@id":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/"},"author":{"name":"Sabrina Lorenzon","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/db9a93dba3500869b86f1eeb1a7b8d14"},"headline":"(Italiano) Criticit\u00e0 relative all\u2019erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 15\/03\/2024","datePublished":"2024-03-14T11:26:21+00:00","dateModified":"2026-01-28T17:16:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/"},"wordCount":163,"image":{"@id":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/atapspa.it\/wp-content\/uploads\/2024\/03\/15.03.2024.png","articleSection":["Non in vista"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/","url":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/","name":"[:it]Criticit\u00e0 relative all\u2019erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 15\/03\/2024[:] - Atap S.p.a.","isPartOf":{"@id":"https:\/\/www.atapspa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/atapspa.it\/wp-content\/uploads\/2024\/03\/15.03.2024.png","datePublished":"2024-03-14T11:26:21+00:00","dateModified":"2026-01-28T17:16:35+00:00","author":{"@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/db9a93dba3500869b86f1eeb1a7b8d14"},"breadcrumb":{"@id":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/#primaryimage","url":"https:\/\/atapspa.it\/wp-content\/uploads\/2024\/03\/15.03.2024.png","contentUrl":"https:\/\/atapspa.it\/wp-content\/uploads\/2024\/03\/15.03.2024.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.atapspa.it\/non-in-vista\/criticita-relative-allerogazione-dei-servizi-di-trasporto-pubblico-locale-atap-nella-giornata-del-15-03-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atapspa.it\/en\/"},{"@type":"ListItem","position":2,"name":"Criticit\u00e0 relative all\u2019erogazione dei servizi di trasporto pubblico locale ATAP nella giornata del 15\/03\/2024"}]},{"@type":"WebSite","@id":"https:\/\/www.atapspa.it\/en\/#website","url":"https:\/\/www.atapspa.it\/en\/","name":"Atap S.p.a.","description":"Atap, in viaggio con voi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atapspa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/db9a93dba3500869b86f1eeb1a7b8d14","name":"Sabrina Lorenzon","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0d00766c1945d4518ecdbc8124af8ffe4396c9936ff79507bf7d3584c037d5ea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0d00766c1945d4518ecdbc8124af8ffe4396c9936ff79507bf7d3584c037d5ea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d00766c1945d4518ecdbc8124af8ffe4396c9936ff79507bf7d3584c037d5ea?s=96&d=mm&r=g","caption":"Sabrina Lorenzon"},"url":"https:\/\/www.atapspa.it\/en\/author\/lorenzon\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 07:00:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/22207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/comments?post=22207"}],"version-history":[{"count":1,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/22207\/revisions"}],"predecessor-version":[{"id":22209,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/22207\/revisions\/22209"}],"wp:attachment":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/media?parent=22207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/categories?post=22207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/tags?post=22207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}