{"id":23375,"date":"2024-10-01T10:52:09","date_gmt":"2024-10-01T09:52:09","guid":{"rendered":"https:\/\/atapspa.it\/?p=23375"},"modified":"2024-10-01T10:52:09","modified_gmt":"2024-10-01T09:52:09","slug":"%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero","status":"publish","type":"post","link":"https:\/\/www.atapspa.it\/en\/news\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/","title":{"rendered":"(Italiano) \ud83d\ude8c Modifica Linea 300 Biella \u2013 Cossato \u2013 Valle Mosso &#8211; Trivero"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.atapspa.it\/it\/wp-json\/wp\/v2\/posts\/23375\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italiano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Italiano.<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-23375","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\/en\/news\/\ud83d\ude8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]\ud83d\ude8c Modifica Linea 300 Biella \u2013 Cossato \u2013 Valle Mosso - Trivero[:] - Atap S.p.a.\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Italiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\/en\/news\/\ud83d\ude8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/\" \/>\n<meta property=\"og:site_name\" content=\"Atap S.p.a.\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-01T09:52:09+00:00\" \/>\n<meta name=\"author\" content=\"Fabrizio Paluan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabrizio Paluan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\\\/en\\\/news\\\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\\\/en\\\/news\\\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\\\/\"},\"author\":{\"name\":\"Fabrizio Paluan\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/608f5ee5f06d7d1b879cba642ae2ba2a\"},\"headline\":\"(Italiano) \ud83d\ude8c Modifica Linea 300 Biella \u2013 Cossato \u2013 Valle Mosso &#8211; Trivero\",\"datePublished\":\"2024-10-01T09:52:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\\\/en\\\/news\\\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\\\/\"},\"wordCount\":79,\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\\\/en\\\/news\\\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\\\/\",\"url\":\"https:\\\/\\\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\\\/en\\\/news\\\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\\\/\",\"name\":\"[:it]\ud83d\ude8c Modifica Linea 300 Biella \u2013 Cossato \u2013 Valle Mosso - Trivero[:] - Atap S.p.a.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\"},\"datePublished\":\"2024-10-01T09:52:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/608f5ee5f06d7d1b879cba642ae2ba2a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\\\/en\\\/news\\\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\\\/en\\\/news\\\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\\\/en\\\/news\\\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(Italiano) \ud83d\ude8c Modifica Linea 300 Biella \u2013 Cossato \u2013 Valle Mosso &#8211; Trivero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\",\"name\":\"Atap S.p.a.\",\"description\":\"Atap, in viaggio con voi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/608f5ee5f06d7d1b879cba642ae2ba2a\",\"name\":\"Fabrizio Paluan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4d38815f2e60ee809e63079219f0e1838f9cfd1386901b355b83ffe6efb788f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4d38815f2e60ee809e63079219f0e1838f9cfd1386901b355b83ffe6efb788f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4d38815f2e60ee809e63079219f0e1838f9cfd1386901b355b83ffe6efb788f?s=96&d=mm&r=g\",\"caption\":\"Fabrizio Paluan\"},\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/author\\\/paluan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]\ud83d\ude8c Modifica Linea 300 Biella \u2013 Cossato \u2013 Valle Mosso - Trivero[:] - Atap S.p.a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\/en\/news\/\ud83d\ude8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/","og_locale":"en_US","og_type":"article","og_title":"[:it]\ud83d\ude8c Modifica Linea 300 Biella \u2013 Cossato \u2013 Valle Mosso - Trivero[:] - Atap S.p.a.","og_description":"Sorry, this entry is only available in Italiano.","og_url":"https:\/\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\/en\/news\/\ud83d\ude8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/","og_site_name":"Atap S.p.a.","article_published_time":"2024-10-01T09:52:09+00:00","author":"Fabrizio Paluan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Fabrizio Paluan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\/en\/news\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/#article","isPartOf":{"@id":"https:\/\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\/en\/news\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/"},"author":{"name":"Fabrizio Paluan","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/608f5ee5f06d7d1b879cba642ae2ba2a"},"headline":"(Italiano) \ud83d\ude8c Modifica Linea 300 Biella \u2013 Cossato \u2013 Valle Mosso &#8211; Trivero","datePublished":"2024-10-01T09:52:09+00:00","mainEntityOfPage":{"@id":"https:\/\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\/en\/news\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/"},"wordCount":79,"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\/en\/news\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/","url":"https:\/\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\/en\/news\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/","name":"[:it]\ud83d\ude8c Modifica Linea 300 Biella \u2013 Cossato \u2013 Valle Mosso - Trivero[:] - Atap S.p.a.","isPartOf":{"@id":"https:\/\/www.atapspa.it\/en\/#website"},"datePublished":"2024-10-01T09:52:09+00:00","author":{"@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/608f5ee5f06d7d1b879cba642ae2ba2a"},"breadcrumb":{"@id":"https:\/\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\/en\/news\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\/en\/news\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ec2-54-77-99-204.eu-west-1.compute.amazonaws.com\/en\/news\/%f0%9f%9a%8c-modifica-linea-300-biella-cossato-valle-mosso-trivero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atapspa.it\/en\/"},{"@type":"ListItem","position":2,"name":"(Italiano) \ud83d\ude8c Modifica Linea 300 Biella \u2013 Cossato \u2013 Valle Mosso &#8211; Trivero"}]},{"@type":"WebSite","@id":"https:\/\/www.atapspa.it\/en\/#website","url":"https:\/\/www.atapspa.it\/en\/","name":"Atap S.p.a.","description":"Atap, in viaggio con voi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atapspa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/608f5ee5f06d7d1b879cba642ae2ba2a","name":"Fabrizio Paluan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c4d38815f2e60ee809e63079219f0e1838f9cfd1386901b355b83ffe6efb788f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c4d38815f2e60ee809e63079219f0e1838f9cfd1386901b355b83ffe6efb788f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c4d38815f2e60ee809e63079219f0e1838f9cfd1386901b355b83ffe6efb788f?s=96&d=mm&r=g","caption":"Fabrizio Paluan"},"url":"https:\/\/www.atapspa.it\/en\/author\/paluan\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 07:00:26","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/23375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/comments?post=23375"}],"version-history":[{"count":1,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/23375\/revisions"}],"predecessor-version":[{"id":23379,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/23375\/revisions\/23379"}],"wp:attachment":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/media?parent=23375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/categories?post=23375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/tags?post=23375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}