{"id":26245,"date":"2025-06-04T09:12:20","date_gmt":"2025-06-04T08:12:20","guid":{"rendered":"https:\/\/atapspa.it\/?p=26245"},"modified":"2025-06-04T09:12:39","modified_gmt":"2025-06-04T08:12:39","slug":"servizi-di-linea-al-termine-dellanno-scolastico-4","status":"publish","type":"post","link":"https:\/\/www.atapspa.it\/en\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/","title":{"rendered":"(Italiano) Servizi di Linea al termine dell\u2019anno scolastico"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.atapspa.it\/it\/wp-json\/wp\/v2\/posts\/26245\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italiano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Italiano.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-26245","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atapspa.it\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:it]Servizi di Linea al termine dell\u2019anno scolastico[:] - Atap S.p.a.\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Italiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atapspa.it\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Atap S.p.a.\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-04T08:12:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T08:12:39+00:00\" \/>\n<meta name=\"author\" content=\"Andrea Dal Ponte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Dal Ponte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/news\\\/servizi-di-linea-al-termine-dellanno-scolastico-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/news\\\/servizi-di-linea-al-termine-dellanno-scolastico-4\\\/\"},\"author\":{\"name\":\"Andrea Dal Ponte\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/22baa47e1d19a8d554984a2ac74ca73a\"},\"headline\":\"(Italiano) Servizi di Linea al termine dell\u2019anno scolastico\",\"datePublished\":\"2025-06-04T08:12:20+00:00\",\"dateModified\":\"2025-06-04T08:12:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/news\\\/servizi-di-linea-al-termine-dellanno-scolastico-4\\\/\"},\"wordCount\":94,\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/news\\\/servizi-di-linea-al-termine-dellanno-scolastico-4\\\/\",\"url\":\"https:\\\/\\\/atapspa.it\\\/news\\\/servizi-di-linea-al-termine-dellanno-scolastico-4\\\/\",\"name\":\"[:it]Servizi di Linea al termine dell\u2019anno scolastico[:] - Atap S.p.a.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\"},\"datePublished\":\"2025-06-04T08:12:20+00:00\",\"dateModified\":\"2025-06-04T08:12:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/22baa47e1d19a8d554984a2ac74ca73a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/news\\\/servizi-di-linea-al-termine-dellanno-scolastico-4\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/atapspa.it\\\/news\\\/servizi-di-linea-al-termine-dellanno-scolastico-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/news\\\/servizi-di-linea-al-termine-dellanno-scolastico-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servizi di Linea al termine dell\u2019anno scolastico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/\",\"name\":\"Atap S.p.a.\",\"description\":\"Atap, in viaggio con voi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/#\\\/schema\\\/person\\\/22baa47e1d19a8d554984a2ac74ca73a\",\"name\":\"Andrea Dal Ponte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g\",\"caption\":\"Andrea Dal Ponte\"},\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/author\\\/dalponte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]Servizi di Linea al termine dell\u2019anno scolastico[:] - Atap S.p.a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atapspa.it\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/","og_locale":"en_US","og_type":"article","og_title":"[:it]Servizi di Linea al termine dell\u2019anno scolastico[:] - Atap S.p.a.","og_description":"Sorry, this entry is only available in Italiano.","og_url":"https:\/\/atapspa.it\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/","og_site_name":"Atap S.p.a.","article_published_time":"2025-06-04T08:12:20+00:00","article_modified_time":"2025-06-04T08:12:39+00:00","author":"Andrea Dal Ponte","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Andrea Dal Ponte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/atapspa.it\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/#article","isPartOf":{"@id":"https:\/\/atapspa.it\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/"},"author":{"name":"Andrea Dal Ponte","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/22baa47e1d19a8d554984a2ac74ca73a"},"headline":"(Italiano) Servizi di Linea al termine dell\u2019anno scolastico","datePublished":"2025-06-04T08:12:20+00:00","dateModified":"2025-06-04T08:12:39+00:00","mainEntityOfPage":{"@id":"https:\/\/atapspa.it\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/"},"wordCount":94,"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/atapspa.it\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/","url":"https:\/\/atapspa.it\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/","name":"[:it]Servizi di Linea al termine dell\u2019anno scolastico[:] - Atap S.p.a.","isPartOf":{"@id":"https:\/\/www.atapspa.it\/en\/#website"},"datePublished":"2025-06-04T08:12:20+00:00","dateModified":"2025-06-04T08:12:39+00:00","author":{"@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/22baa47e1d19a8d554984a2ac74ca73a"},"breadcrumb":{"@id":"https:\/\/atapspa.it\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atapspa.it\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/atapspa.it\/news\/servizi-di-linea-al-termine-dellanno-scolastico-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atapspa.it\/en\/"},{"@type":"ListItem","position":2,"name":"Servizi di Linea al termine dell\u2019anno scolastico"}]},{"@type":"WebSite","@id":"https:\/\/www.atapspa.it\/en\/#website","url":"https:\/\/www.atapspa.it\/en\/","name":"Atap S.p.a.","description":"Atap, in viaggio con voi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atapspa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.atapspa.it\/en\/#\/schema\/person\/22baa47e1d19a8d554984a2ac74ca73a","name":"Andrea Dal Ponte","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79b7b3ffc7ad73a7a3c0b345773982fb2742d39185ba9036da9d4b2b1f57f10d?s=96&d=mm&r=g","caption":"Andrea Dal Ponte"},"url":"https:\/\/www.atapspa.it\/en\/author\/dalponte\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 07:01:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/26245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/comments?post=26245"}],"version-history":[{"count":2,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/26245\/revisions"}],"predecessor-version":[{"id":26248,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/26245\/revisions\/26248"}],"wp:attachment":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/media?parent=26245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/categories?post=26245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/tags?post=26245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}