{"id":7080,"date":"2017-12-21T17:24:30","date_gmt":"2017-12-21T16:24:30","guid":{"rendered":"http:\/\/atapspa.it\/?p=7080"},"modified":"2017-12-21T17:24:30","modified_gmt":"2017-12-21T16:24:30","slug":"servizi-di-linea-durante-il-periodo-natalizio-4","status":"publish","type":"post","link":"https:\/\/www.atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/","title":{"rendered":"Servizi di Linea durante il periodo natalizio"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.atapspa.it\/it\/wp-json\/wp\/v2\/posts\/7080\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"Italiano\">Italiano<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Italiano.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7080","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servizi di Linea durante il periodo natalizio - Atap S.p.a.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servizi di Linea durante il periodo natalizio - Atap S.p.a.\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Italiano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Atap S.p.a.\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-21T16:24:30+00:00\" \/>\n<meta name=\"author\" content=\"Paolo Mistrangelo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paolo Mistrangelo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/news\\\/servizi-di-linea-durante-il-periodo-natalizio-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/news\\\/servizi-di-linea-durante-il-periodo-natalizio-4\\\/\"},\"author\":{\"name\":\"Paolo Mistrangelo\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/#\\\/schema\\\/person\\\/13a62c4755f940fe30536d793f60658d\"},\"headline\":\"Servizi di Linea durante il periodo natalizio\",\"datePublished\":\"2017-12-21T16:24:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/news\\\/servizi-di-linea-durante-il-periodo-natalizio-4\\\/\"},\"wordCount\":136,\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/news\\\/servizi-di-linea-durante-il-periodo-natalizio-4\\\/\",\"url\":\"https:\\\/\\\/atapspa.it\\\/en\\\/news\\\/servizi-di-linea-durante-il-periodo-natalizio-4\\\/\",\"name\":\"Servizi di Linea durante il periodo natalizio - Atap S.p.a.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/#website\"},\"datePublished\":\"2017-12-21T16:24:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/#\\\/schema\\\/person\\\/13a62c4755f940fe30536d793f60658d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/news\\\/servizi-di-linea-durante-il-periodo-natalizio-4\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/atapspa.it\\\/en\\\/news\\\/servizi-di-linea-durante-il-periodo-natalizio-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/atapspa.it\\\/en\\\/news\\\/servizi-di-linea-durante-il-periodo-natalizio-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.atapspa.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servizi di Linea durante il periodo natalizio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/#website\",\"url\":\"https:\\\/\\\/www.atapspa.it\\\/\",\"name\":\"Atap S.p.a.\",\"description\":\"Atap, in viaggio con voi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.atapspa.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.atapspa.it\\\/#\\\/schema\\\/person\\\/13a62c4755f940fe30536d793f60658d\",\"name\":\"Paolo Mistrangelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6cf4707be0cfffe1d92f26894d35f65df8aae6e1c0a31bdd6af5f534e3bd875?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6cf4707be0cfffe1d92f26894d35f65df8aae6e1c0a31bdd6af5f534e3bd875?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e6cf4707be0cfffe1d92f26894d35f65df8aae6e1c0a31bdd6af5f534e3bd875?s=96&d=mm&r=g\",\"caption\":\"Paolo Mistrangelo\"},\"url\":\"https:\\\/\\\/www.atapspa.it\\\/en\\\/author\\\/ilmistra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servizi di Linea durante il periodo natalizio - Atap S.p.a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/","og_locale":"en_US","og_type":"article","og_title":"Servizi di Linea durante il periodo natalizio - Atap S.p.a.","og_description":"Sorry, this entry is only available in Italiano.","og_url":"https:\/\/atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/","og_site_name":"Atap S.p.a.","article_published_time":"2017-12-21T16:24:30+00:00","author":"Paolo Mistrangelo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Paolo Mistrangelo","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/#article","isPartOf":{"@id":"https:\/\/atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/"},"author":{"name":"Paolo Mistrangelo","@id":"https:\/\/www.atapspa.it\/#\/schema\/person\/13a62c4755f940fe30536d793f60658d"},"headline":"Servizi di Linea durante il periodo natalizio","datePublished":"2017-12-21T16:24:30+00:00","mainEntityOfPage":{"@id":"https:\/\/atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/"},"wordCount":136,"articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/","url":"https:\/\/atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/","name":"Servizi di Linea durante il periodo natalizio - Atap S.p.a.","isPartOf":{"@id":"https:\/\/www.atapspa.it\/#website"},"datePublished":"2017-12-21T16:24:30+00:00","author":{"@id":"https:\/\/www.atapspa.it\/#\/schema\/person\/13a62c4755f940fe30536d793f60658d"},"breadcrumb":{"@id":"https:\/\/atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/atapspa.it\/en\/news\/servizi-di-linea-durante-il-periodo-natalizio-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atapspa.it\/"},{"@type":"ListItem","position":2,"name":"Servizi di Linea durante il periodo natalizio"}]},{"@type":"WebSite","@id":"https:\/\/www.atapspa.it\/#website","url":"https:\/\/www.atapspa.it\/","name":"Atap S.p.a.","description":"Atap, in viaggio con voi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atapspa.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.atapspa.it\/#\/schema\/person\/13a62c4755f940fe30536d793f60658d","name":"Paolo Mistrangelo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e6cf4707be0cfffe1d92f26894d35f65df8aae6e1c0a31bdd6af5f534e3bd875?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e6cf4707be0cfffe1d92f26894d35f65df8aae6e1c0a31bdd6af5f534e3bd875?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e6cf4707be0cfffe1d92f26894d35f65df8aae6e1c0a31bdd6af5f534e3bd875?s=96&d=mm&r=g","caption":"Paolo Mistrangelo"},"url":"https:\/\/www.atapspa.it\/en\/author\/ilmistra\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 20:14:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/7080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/comments?post=7080"}],"version-history":[{"count":0,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/posts\/7080\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/media?parent=7080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/categories?post=7080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.atapspa.it\/en\/wp-json\/wp\/v2\/tags?post=7080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}